{"id":4864,"date":"2023-12-19T14:15:30","date_gmt":"2023-12-19T14:15:30","guid":{"rendered":"https:\/\/delikatess.eu\/product\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\/"},"modified":"2024-02-11T12:15:59","modified_gmt":"2024-02-11T12:15:59","slug":"%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3","status":"publish","type":"product","link":"https:\/\/delikatess.eu\/ru\/product\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\/","title":{"rendered":"\u0425\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435 \u043a\u0443\u0440\u0438\u043d\u044b\u0435 \u0447\u0438\u043f\u0441\u044b 60 \u0433"},"content":{"rendered":"<p>\u0421\u043e\u0441\u0442\u0430\u0432: \u043a\u0443\u0440\u0438\u043d\u0430\u044f \u043a\u043e\u0436\u0430, \u0440\u0430\u043f\u0441\u043e\u0432\u043e\u0435 \u043c\u0430\u0441\u043b\u043e, \u0441\u043e\u043b\u044c, <strong>\u0447\u0435\u0441\u043d\u043e\u043a, \u043f\u0430\u043f\u0440\u0438\u043a\u0430<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0421\u043e\u0441\u0442\u0430\u0432: \u043a\u0443\u0440\u0438\u043d\u0430\u044f \u043a\u043e\u0436\u0430, \u0440\u0430\u043f\u0441\u043e\u0432\u043e\u0435 \u043c\u0430\u0441\u043b\u043e, \u0441\u043e\u043b\u044c, <strong>\u0447\u0435\u0441\u043d\u043e\u043a, \u043f\u0430\u043f\u0440\u0438\u043a\u0430<\/strong>.<\/p>\n","protected":false},"featured_media":4814,"template":"","meta":[],"product_brand":[],"product_cat":[139,234],"product_tag":[235,236],"class_list":{"0":"post-4864","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-139","7":"product_cat-234","8":"product_tag-235","9":"product_tag--ru","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0425\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435 \u043a\u0443\u0440\u0438\u043d\u044b\u0435 \u0447\u0438\u043f\u0441\u044b 60 \u0433 - Delikatess Food O&Uuml;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/delikatess.eu\/ru\/product\/\u0445\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435-\u043a\u0443\u0440\u0438\u043d\u044b\u0435-\u0447\u0438\u043f\u0441\u044b-60-\u0433\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0425\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435 \u043a\u0443\u0440\u0438\u043d\u044b\u0435 \u0447\u0438\u043f\u0441\u044b 60 \u0433 - Delikatess Food O&Uuml;\" \/>\n<meta property=\"og:description\" content=\"\u0421\u043e\u0441\u0442\u0430\u0432: \u043a\u0443\u0440\u0438\u043d\u0430\u044f \u043a\u043e\u0436\u0430, \u0440\u0430\u043f\u0441\u043e\u0432\u043e\u0435 \u043c\u0430\u0441\u043b\u043e, \u0441\u043e\u043b\u044c, \u0447\u0435\u0441\u043d\u043e\u043a, \u043f\u0430\u043f\u0440\u0438\u043a\u0430.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/delikatess.eu\/ru\/product\/\u0445\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435-\u043a\u0443\u0440\u0438\u043d\u044b\u0435-\u0447\u0438\u043f\u0441\u044b-60-\u0433\/\" \/>\n<meta property=\"og:site_name\" content=\"Delikatess Food O&Uuml;\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/delikatessfood\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-11T12:15:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/delikatess.eu\/wp-content\/uploads\/2023\/12\/kana_kropsud_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"791\" \/>\n\t<meta property=\"og:image:height\" content=\"1187\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\\\/\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\\\/\",\"name\":\"\u0425\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435 \u043a\u0443\u0440\u0438\u043d\u044b\u0435 \u0447\u0438\u043f\u0441\u044b 60 \u0433 - Delikatess Food O&Uuml;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/delikatess.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/kana_kropsud_2.jpg\",\"datePublished\":\"2023-12-19T14:15:30+00:00\",\"dateModified\":\"2024-02-11T12:15:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/kana_kropsud_2.jpg\",\"contentUrl\":\"https:\\\/\\\/delikatess.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/kana_kropsud_2.jpg\",\"width\":791,\"height\":1187},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041c\u0430\u0433\u0430\u0437\u0438\u043d\",\"item\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/%d0%bc%d0%b0%d0%b3%d0%b0%d0%b7%d0%b8%d0%bd\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0425\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435 \u043a\u0443\u0440\u0438\u043d\u044b\u0435 \u0447\u0438\u043f\u0441\u044b 60 \u0433\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#website\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/\",\"name\":\"Delikatess Food O&Uuml;\",\"description\":\"Handmade With Love\",\"publisher\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/delikatess.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#organization\",\"name\":\"Delikatess\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Delikatess_logo_labit-1.png\",\"contentUrl\":\"https:\\\/\\\/delikatess.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Delikatess_logo_labit-1.png\",\"width\":801,\"height\":229,\"caption\":\"Delikatess\"},\"image\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/delikatessfood\\\/\",\"https:\\\/\\\/www.instagram.com\\\/delikatess.eu\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0425\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435 \u043a\u0443\u0440\u0438\u043d\u044b\u0435 \u0447\u0438\u043f\u0441\u044b 60 \u0433 - Delikatess Food O&Uuml;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/delikatess.eu\/ru\/product\/\u0445\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435-\u043a\u0443\u0440\u0438\u043d\u044b\u0435-\u0447\u0438\u043f\u0441\u044b-60-\u0433\/","og_locale":"ru_RU","og_type":"article","og_title":"\u0425\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435 \u043a\u0443\u0440\u0438\u043d\u044b\u0435 \u0447\u0438\u043f\u0441\u044b 60 \u0433 - Delikatess Food O&Uuml;","og_description":"\u0421\u043e\u0441\u0442\u0430\u0432: \u043a\u0443\u0440\u0438\u043d\u0430\u044f \u043a\u043e\u0436\u0430, \u0440\u0430\u043f\u0441\u043e\u0432\u043e\u0435 \u043c\u0430\u0441\u043b\u043e, \u0441\u043e\u043b\u044c, \u0447\u0435\u0441\u043d\u043e\u043a, \u043f\u0430\u043f\u0440\u0438\u043a\u0430.","og_url":"https:\/\/delikatess.eu\/ru\/product\/\u0445\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435-\u043a\u0443\u0440\u0438\u043d\u044b\u0435-\u0447\u0438\u043f\u0441\u044b-60-\u0433\/","og_site_name":"Delikatess Food O&Uuml;","article_publisher":"https:\/\/www.facebook.com\/delikatessfood\/","article_modified_time":"2024-02-11T12:15:59+00:00","og_image":[{"width":791,"height":1187,"url":"https:\/\/delikatess.eu\/wp-content\/uploads\/2023\/12\/kana_kropsud_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/delikatess.eu\/ru\/product\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\/","url":"https:\/\/delikatess.eu\/ru\/product\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\/","name":"\u0425\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435 \u043a\u0443\u0440\u0438\u043d\u044b\u0435 \u0447\u0438\u043f\u0441\u044b 60 \u0433 - Delikatess Food O&Uuml;","isPartOf":{"@id":"https:\/\/delikatess.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/delikatess.eu\/ru\/product\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\/#primaryimage"},"image":{"@id":"https:\/\/delikatess.eu\/ru\/product\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\/#primaryimage"},"thumbnailUrl":"https:\/\/delikatess.eu\/wp-content\/uploads\/2023\/12\/kana_kropsud_2.jpg","datePublished":"2023-12-19T14:15:30+00:00","dateModified":"2024-02-11T12:15:59+00:00","breadcrumb":{"@id":"https:\/\/delikatess.eu\/ru\/product\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/delikatess.eu\/ru\/product\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/delikatess.eu\/ru\/product\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\/#primaryimage","url":"https:\/\/delikatess.eu\/wp-content\/uploads\/2023\/12\/kana_kropsud_2.jpg","contentUrl":"https:\/\/delikatess.eu\/wp-content\/uploads\/2023\/12\/kana_kropsud_2.jpg","width":791,"height":1187},{"@type":"BreadcrumbList","@id":"https:\/\/delikatess.eu\/ru\/product\/%d1%85%d1%80%d1%83%d1%81%d1%82%d1%8f%d1%89%d0%b8%d0%b5-%d0%ba%d1%83%d1%80%d0%b8%d0%bd%d1%8b%d0%b5-%d1%87%d0%b8%d0%bf%d1%81%d1%8b-60-%d0%b3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/delikatess.eu\/ru\/"},{"@type":"ListItem","position":2,"name":"\u041c\u0430\u0433\u0430\u0437\u0438\u043d","item":"https:\/\/delikatess.eu\/ru\/%d0%bc%d0%b0%d0%b3%d0%b0%d0%b7%d0%b8%d0%bd\/"},{"@type":"ListItem","position":3,"name":"\u0425\u0440\u0443\u0441\u0442\u044f\u0449\u0438\u0435 \u043a\u0443\u0440\u0438\u043d\u044b\u0435 \u0447\u0438\u043f\u0441\u044b 60 \u0433"}]},{"@type":"WebSite","@id":"https:\/\/delikatess.eu\/#website","url":"https:\/\/delikatess.eu\/","name":"Delikatess Food O&Uuml;","description":"Handmade With Love","publisher":{"@id":"https:\/\/delikatess.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/delikatess.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/delikatess.eu\/#organization","name":"Delikatess","url":"https:\/\/delikatess.eu\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/delikatess.eu\/#\/schema\/logo\/image\/","url":"https:\/\/delikatess.eu\/wp-content\/uploads\/2022\/07\/Delikatess_logo_labit-1.png","contentUrl":"https:\/\/delikatess.eu\/wp-content\/uploads\/2022\/07\/Delikatess_logo_labit-1.png","width":801,"height":229,"caption":"Delikatess"},"image":{"@id":"https:\/\/delikatess.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/delikatessfood\/","https:\/\/www.instagram.com\/delikatess.eu\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/product\/4864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/media\/4814"}],"wp:attachment":[{"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/media?parent=4864"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/product_brand?post=4864"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/product_cat?post=4864"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/product_tag?post=4864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}