{"id":4273,"date":"2020-04-05T11:56:07","date_gmt":"2020-04-05T11:56:07","guid":{"rendered":"https:\/\/delikatess.eu\/product\/pekk\/"},"modified":"2022-07-18T13:57:10","modified_gmt":"2022-07-18T13:57:10","slug":"%d1%81%d0%b0%d0%bb%d0%be","status":"publish","type":"product","link":"https:\/\/delikatess.eu\/ru\/product\/%d1%81%d0%b0%d0%bb%d0%be\/","title":{"rendered":"\u0421\u0430\u043b\u043e"},"content":{"rendered":"<p>\u0421\u0430\u043b\u043e, \u043f\u0440\u0438\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u043d\u043e\u0435 \u0447\u0435\u0440\u043d\u044b\u043c \u043f\u0435\u0440\u0446\u0435\u043c. \u041f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0434\u043b\u044f \u0431\u0443\u0442\u0435\u0440\u0431\u0440\u043e\u0434\u0430 \u0438 \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u0437\u0430\u043a\u0443\u0441\u043a\u0438.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0421\u0430\u043b\u043e, \u043f\u0440\u0438\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u043d\u043e\u0435 \u0447\u0435\u0440\u043d\u044b\u043c \u043f\u0435\u0440\u0446\u0435\u043c. \u041f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0434\u043b\u044f \u0431\u0443\u0442\u0435\u0440\u0431\u0440\u043e\u0434\u0430 \u0438 \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u0437\u0430\u043a\u0443\u0441\u043a\u0438.<\/p>\n","protected":false},"featured_media":4585,"template":"","meta":[],"product_brand":[],"product_cat":[139,147],"product_tag":[],"class_list":{"0":"post-4273","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-139","7":"product_cat-147","9":"first","10":"instock","11":"sale","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0421\u0430\u043b\u043e - Delikatess Food O&Uuml;<\/title>\n<meta name=\"description\" content=\"\u0421\u0430\u043b\u043e, \u043f\u0440\u0438\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u043d\u043e\u0435 \u0447\u0435\u0440\u043d\u044b\u043c \u043f\u0435\u0440\u0446\u0435\u043c. \u0418\u0434\u0435\u0430\u043b\u044c\u043d\u043e \u043f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0434\u043b\u044f \u0431\u0443\u0442\u0435\u0440\u0431\u0440\u043e\u0434\u0430 \u0438 \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u0437\u0430\u043a\u0443\u0441\u043a\u0438. \u0411\u044b\u0441\u0442\u0440\u0430\u044f \u0438 \u0443\u0434\u043e\u0431\u043d\u0430\u044f \u0434\u043e\u0441\u0442\u0430\u0432\u043a\u0430!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/delikatess.eu\/ru\/product\/\u0441\u0430\u043b\u043e\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0421\u0430\u043b\u043e - Delikatess Food O&Uuml;\" \/>\n<meta property=\"og:description\" content=\"\u0421\u0430\u043b\u043e, \u043f\u0440\u0438\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u043d\u043e\u0435 \u0447\u0435\u0440\u043d\u044b\u043c \u043f\u0435\u0440\u0446\u0435\u043c. \u0418\u0434\u0435\u0430\u043b\u044c\u043d\u043e \u043f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0434\u043b\u044f \u0431\u0443\u0442\u0435\u0440\u0431\u0440\u043e\u0434\u0430 \u0438 \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u0437\u0430\u043a\u0443\u0441\u043a\u0438. \u0411\u044b\u0441\u0442\u0440\u0430\u044f \u0438 \u0443\u0434\u043e\u0431\u043d\u0430\u044f \u0434\u043e\u0441\u0442\u0430\u0432\u043a\u0430!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/delikatess.eu\/ru\/product\/\u0441\u0430\u043b\u043e\/\" \/>\n<meta property=\"og:site_name\" content=\"Delikatess Food O&Uuml;\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/delikatessfood\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-18T13:57:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/delikatess.eu\/wp-content\/uploads\/2020\/04\/ukraina_pekk.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1246\" \/>\n\t<meta property=\"og:image:height\" content=\"830\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%81%d0%b0%d0%bb%d0%be\\\/\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%81%d0%b0%d0%bb%d0%be\\\/\",\"name\":\"\u0421\u0430\u043b\u043e - Delikatess Food O&Uuml;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%81%d0%b0%d0%bb%d0%be\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%81%d0%b0%d0%bb%d0%be\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/delikatess.eu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ukraina_pekk.jpg\",\"datePublished\":\"2020-04-05T11:56:07+00:00\",\"dateModified\":\"2022-07-18T13:57:10+00:00\",\"description\":\"\u0421\u0430\u043b\u043e, \u043f\u0440\u0438\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u043d\u043e\u0435 \u0447\u0435\u0440\u043d\u044b\u043c \u043f\u0435\u0440\u0446\u0435\u043c. \u0418\u0434\u0435\u0430\u043b\u044c\u043d\u043e \u043f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0434\u043b\u044f \u0431\u0443\u0442\u0435\u0440\u0431\u0440\u043e\u0434\u0430 \u0438 \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u0437\u0430\u043a\u0443\u0441\u043a\u0438. \u0411\u044b\u0441\u0442\u0440\u0430\u044f \u0438 \u0443\u0434\u043e\u0431\u043d\u0430\u044f \u0434\u043e\u0441\u0442\u0430\u0432\u043a\u0430!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%81%d0%b0%d0%bb%d0%be\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%81%d0%b0%d0%bb%d0%be\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%81%d0%b0%d0%bb%d0%be\\\/#primaryimage\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ukraina_pekk.jpg\",\"contentUrl\":\"https:\\\/\\\/delikatess.eu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ukraina_pekk.jpg\",\"width\":1246,\"height\":830},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/product\\\/%d1%81%d0%b0%d0%bb%d0%be\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041c\u0430\u0433\u0430\u0437\u0438\u043d\",\"item\":\"https:\\\/\\\/delikatess.eu\\\/ru\\\/%d0%bc%d0%b0%d0%b3%d0%b0%d0%b7%d0%b8%d0%bd\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0421\u0430\u043b\u043e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#website\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/\",\"name\":\"Delikatess Food O&Uuml;\",\"description\":\"Handmade With Love\",\"publisher\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/delikatess.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#organization\",\"name\":\"Delikatess\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Delikatess_logo_labit-1.png\",\"contentUrl\":\"https:\\\/\\\/delikatess.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Delikatess_logo_labit-1.png\",\"width\":801,\"height\":229,\"caption\":\"Delikatess\"},\"image\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/delikatessfood\\\/\",\"https:\\\/\\\/www.instagram.com\\\/delikatess.eu\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0421\u0430\u043b\u043e - Delikatess Food O&Uuml;","description":"\u0421\u0430\u043b\u043e, \u043f\u0440\u0438\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u043d\u043e\u0435 \u0447\u0435\u0440\u043d\u044b\u043c \u043f\u0435\u0440\u0446\u0435\u043c. \u0418\u0434\u0435\u0430\u043b\u044c\u043d\u043e \u043f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0434\u043b\u044f \u0431\u0443\u0442\u0435\u0440\u0431\u0440\u043e\u0434\u0430 \u0438 \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u0437\u0430\u043a\u0443\u0441\u043a\u0438. \u0411\u044b\u0441\u0442\u0440\u0430\u044f \u0438 \u0443\u0434\u043e\u0431\u043d\u0430\u044f \u0434\u043e\u0441\u0442\u0430\u0432\u043a\u0430!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/delikatess.eu\/ru\/product\/\u0441\u0430\u043b\u043e\/","og_locale":"ru_RU","og_type":"article","og_title":"\u0421\u0430\u043b\u043e - Delikatess Food O&Uuml;","og_description":"\u0421\u0430\u043b\u043e, \u043f\u0440\u0438\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u043d\u043e\u0435 \u0447\u0435\u0440\u043d\u044b\u043c \u043f\u0435\u0440\u0446\u0435\u043c. \u0418\u0434\u0435\u0430\u043b\u044c\u043d\u043e \u043f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0434\u043b\u044f \u0431\u0443\u0442\u0435\u0440\u0431\u0440\u043e\u0434\u0430 \u0438 \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u0437\u0430\u043a\u0443\u0441\u043a\u0438. \u0411\u044b\u0441\u0442\u0440\u0430\u044f \u0438 \u0443\u0434\u043e\u0431\u043d\u0430\u044f \u0434\u043e\u0441\u0442\u0430\u0432\u043a\u0430!","og_url":"https:\/\/delikatess.eu\/ru\/product\/\u0441\u0430\u043b\u043e\/","og_site_name":"Delikatess Food O&Uuml;","article_publisher":"https:\/\/www.facebook.com\/delikatessfood\/","article_modified_time":"2022-07-18T13:57:10+00:00","og_image":[{"width":1246,"height":830,"url":"https:\/\/delikatess.eu\/wp-content\/uploads\/2020\/04\/ukraina_pekk.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/delikatess.eu\/ru\/product\/%d1%81%d0%b0%d0%bb%d0%be\/","url":"https:\/\/delikatess.eu\/ru\/product\/%d1%81%d0%b0%d0%bb%d0%be\/","name":"\u0421\u0430\u043b\u043e - Delikatess Food O&Uuml;","isPartOf":{"@id":"https:\/\/delikatess.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/delikatess.eu\/ru\/product\/%d1%81%d0%b0%d0%bb%d0%be\/#primaryimage"},"image":{"@id":"https:\/\/delikatess.eu\/ru\/product\/%d1%81%d0%b0%d0%bb%d0%be\/#primaryimage"},"thumbnailUrl":"https:\/\/delikatess.eu\/wp-content\/uploads\/2020\/04\/ukraina_pekk.jpg","datePublished":"2020-04-05T11:56:07+00:00","dateModified":"2022-07-18T13:57:10+00:00","description":"\u0421\u0430\u043b\u043e, \u043f\u0440\u0438\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u043d\u043e\u0435 \u0447\u0435\u0440\u043d\u044b\u043c \u043f\u0435\u0440\u0446\u0435\u043c. \u0418\u0434\u0435\u0430\u043b\u044c\u043d\u043e \u043f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0434\u043b\u044f \u0431\u0443\u0442\u0435\u0440\u0431\u0440\u043e\u0434\u0430 \u0438 \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u0437\u0430\u043a\u0443\u0441\u043a\u0438. \u0411\u044b\u0441\u0442\u0440\u0430\u044f \u0438 \u0443\u0434\u043e\u0431\u043d\u0430\u044f \u0434\u043e\u0441\u0442\u0430\u0432\u043a\u0430!","breadcrumb":{"@id":"https:\/\/delikatess.eu\/ru\/product\/%d1%81%d0%b0%d0%bb%d0%be\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/delikatess.eu\/ru\/product\/%d1%81%d0%b0%d0%bb%d0%be\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/delikatess.eu\/ru\/product\/%d1%81%d0%b0%d0%bb%d0%be\/#primaryimage","url":"https:\/\/delikatess.eu\/wp-content\/uploads\/2020\/04\/ukraina_pekk.jpg","contentUrl":"https:\/\/delikatess.eu\/wp-content\/uploads\/2020\/04\/ukraina_pekk.jpg","width":1246,"height":830},{"@type":"BreadcrumbList","@id":"https:\/\/delikatess.eu\/ru\/product\/%d1%81%d0%b0%d0%bb%d0%be\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/delikatess.eu\/ru\/"},{"@type":"ListItem","position":2,"name":"\u041c\u0430\u0433\u0430\u0437\u0438\u043d","item":"https:\/\/delikatess.eu\/ru\/%d0%bc%d0%b0%d0%b3%d0%b0%d0%b7%d0%b8%d0%bd\/"},{"@type":"ListItem","position":3,"name":"\u0421\u0430\u043b\u043e"}]},{"@type":"WebSite","@id":"https:\/\/delikatess.eu\/#website","url":"https:\/\/delikatess.eu\/","name":"Delikatess Food O&Uuml;","description":"Handmade With Love","publisher":{"@id":"https:\/\/delikatess.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/delikatess.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/delikatess.eu\/#organization","name":"Delikatess","url":"https:\/\/delikatess.eu\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/delikatess.eu\/#\/schema\/logo\/image\/","url":"https:\/\/delikatess.eu\/wp-content\/uploads\/2022\/07\/Delikatess_logo_labit-1.png","contentUrl":"https:\/\/delikatess.eu\/wp-content\/uploads\/2022\/07\/Delikatess_logo_labit-1.png","width":801,"height":229,"caption":"Delikatess"},"image":{"@id":"https:\/\/delikatess.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/delikatessfood\/","https:\/\/www.instagram.com\/delikatess.eu\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/product\/4273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/media\/4585"}],"wp:attachment":[{"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/media?parent=4273"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/product_brand?post=4273"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/product_cat?post=4273"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/delikatess.eu\/ru\/wp-json\/wp\/v2\/product_tag?post=4273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}