{"id":314,"count":0,"description":"","link":"https:\/\/delikatess.eu\/en\/product-category\/uncategorized-en\/","name":"Uncategorized","slug":"uncategorized-en","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uncategorized - Delikatess Food O&Uuml;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/delikatess.eu\/en\/product-category\/uncategorized-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncategorized - Delikatess Food O&Uuml;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/delikatess.eu\/en\/product-category\/uncategorized-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Delikatess Food O&Uuml;\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/en\\\/product-category\\\/uncategorized-en\\\/\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/en\\\/product-category\\\/uncategorized-en\\\/\",\"name\":\"Uncategorized - Delikatess Food O&Uuml;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/en\\\/product-category\\\/uncategorized-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/en\\\/product-category\\\/uncategorized-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/delikatess.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#website\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/\",\"name\":\"Delikatess Food O&Uuml;\",\"description\":\"Handmade With Love\",\"publisher\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/delikatess.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#organization\",\"name\":\"Delikatess\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/delikatess.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Delikatess_logo_labit-1.png\",\"contentUrl\":\"https:\\\/\\\/delikatess.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Delikatess_logo_labit-1.png\",\"width\":801,\"height\":229,\"caption\":\"Delikatess\"},\"image\":{\"@id\":\"https:\\\/\\\/delikatess.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/delikatessfood\\\/\",\"https:\\\/\\\/www.instagram.com\\\/delikatess.eu\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uncategorized - Delikatess Food O&Uuml;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/delikatess.eu\/en\/product-category\/uncategorized-en\/","og_locale":"en_US","og_type":"article","og_title":"Uncategorized - Delikatess Food O&Uuml;","og_url":"https:\/\/delikatess.eu\/en\/product-category\/uncategorized-en\/","og_site_name":"Delikatess Food O&Uuml;","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/delikatess.eu\/en\/product-category\/uncategorized-en\/","url":"https:\/\/delikatess.eu\/en\/product-category\/uncategorized-en\/","name":"Uncategorized - Delikatess Food O&Uuml;","isPartOf":{"@id":"https:\/\/delikatess.eu\/#website"},"breadcrumb":{"@id":"https:\/\/delikatess.eu\/en\/product-category\/uncategorized-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/delikatess.eu\/en\/product-category\/uncategorized-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/delikatess.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"https:\/\/delikatess.eu\/#website","url":"https:\/\/delikatess.eu\/","name":"Delikatess Food O&Uuml;","description":"Handmade With Love","publisher":{"@id":"https:\/\/delikatess.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/delikatess.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/delikatess.eu\/#organization","name":"Delikatess","url":"https:\/\/delikatess.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/delikatess.eu\/#\/schema\/logo\/image\/","url":"https:\/\/delikatess.eu\/wp-content\/uploads\/2022\/07\/Delikatess_logo_labit-1.png","contentUrl":"https:\/\/delikatess.eu\/wp-content\/uploads\/2022\/07\/Delikatess_logo_labit-1.png","width":801,"height":229,"caption":"Delikatess"},"image":{"@id":"https:\/\/delikatess.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/delikatessfood\/","https:\/\/www.instagram.com\/delikatess.eu\/"]}]}},"_links":{"self":[{"href":"https:\/\/delikatess.eu\/en\/wp-json\/wp\/v2\/product_cat\/314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delikatess.eu\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/delikatess.eu\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/delikatess.eu\/en\/wp-json\/wp\/v2\/product?product_cat=314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}